{"id":662,"date":"2019-05-16T09:46:11","date_gmt":"2019-05-16T09:46:11","guid":{"rendered":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/bg-2.png"},"modified":"2022-01-28T12:06:38","modified_gmt":"2022-01-28T05:06:38","slug":"slider_2","status":"inherit","type":"attachment","link":"https:\/\/www.forest.go.th\/ppd\/slider_2\/","title":{"rendered":"slider-2-\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49"},"author":221,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-662","attachment","type-attachment","status-inherit","czr-hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2.png'><img decoding=\"async\" width=\"300\" height=\"69\" src=\"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-300x69.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-300x69.png 300w, https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-768x177.png 768w, https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-1024x236.png 1024w, https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2.png 1304w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1304,"height":301,"file":"2017\/12\/slider_2.png","sizes":{"thumbnail":{"file":"slider_2-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-150x150.png"},"medium":{"file":"slider_2-300x69.png","width":300,"height":69,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-300x69.png"},"medium_large":{"file":"slider_2-768x177.png","width":768,"height":177,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-768x177.png"},"large":{"file":"slider_2-1024x236.png","width":1024,"height":236,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-1024x236.png"},"tc-grid-full":{"file":"slider_2-1110x301.png","width":1110,"height":301,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-1110x301.png"},"tc-grid":{"file":"slider_2-570x301.png","width":570,"height":301,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-570x301.png"},"tc-thumb":{"file":"slider_2-270x250.png","width":270,"height":250,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-270x250.png"},"slider-full":{"file":"slider_2-1304x300.png","width":1304,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-1304x300.png"},"slider":{"file":"slider_2-1110x300.png","width":1110,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-1110x300.png"},"tc-sq-thumb":{"file":"slider_2-510x301.png","width":510,"height":301,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-510x301.png"},"tc-ws-thumb":{"file":"slider_2-1110x301.png","width":1110,"height":301,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-1110x301.png"},"tc-ws-small-thumb":{"file":"slider_2-528x297.png","width":528,"height":297,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-528x297.png"},"tc-slider-small":{"file":"slider_2-517x141.png","width":517,"height":141,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2-517x141.png"},"full":{"file":"slider_2.png","width":1304,"height":301,"mime_type":"image\/png","source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.forest.go.th\/ppd\/wp-content\/uploads\/sites\/99\/2017\/12\/slider_2.png","_links":{"self":[{"href":"https:\/\/www.forest.go.th\/ppd\/wp-json\/wp\/v2\/media\/662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest.go.th\/ppd\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.forest.go.th\/ppd\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/ppd\/wp-json\/wp\/v2\/users\/221"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/ppd\/wp-json\/wp\/v2\/comments?post=662"}]}}