{"id":17094,"date":"2021-09-20T12:14:14","date_gmt":"2021-09-20T05:14:14","guid":{"rendered":"https:\/\/www.forest.go.th\/phitsanulok\/?p=17094"},"modified":"2021-09-20T12:14:42","modified_gmt":"2021-09-20T05:14:42","slug":"%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9b%e0%b8%99%e0%b8%b2%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b9%88%e0%b8%b2%e0%b9%84%e0%b8%a1%e0%b9%89-125-%e0%b8%9b%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/www.forest.go.th\/phitsanulok\/th\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9b%e0%b8%99%e0%b8%b2%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b9%88%e0%b8%b2%e0%b9%84%e0%b8%a1%e0%b9%89-125-%e0%b8%9b%e0%b8%b5\/","title":{"rendered":"\u0e27\u0e31\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e32\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 125 \u0e1b\u0e35"},"content":{"rendered":"\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64.png\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"1024\" src=\"https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64-709x1024.png\" alt=\"\" class=\"wp-image-17098\" srcset=\"https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64-709x1024.png 709w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64-208x300.png 208w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64-768x1109.png 768w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64-1064x1536.png 1064w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/18-9-64-1418x2048.png 1418w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"1024\" src=\"https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-709x1024.jpg\" alt=\"\" class=\"wp-image-17099\" srcset=\"https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-709x1024.jpg 709w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-208x300.jpg 208w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-768x1109.jpg 768w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-1063x1536.jpg 1063w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-1418x2048.jpg 1418w, https:\/\/www.forest.go.th\/phitsanulok\/wp-content\/uploads\/sites\/51\/2021\/09\/\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e08-\u0e19\u0e1b\u0e1e.\u0e19\u0e19-18-9-64-scaled.jpg 1772w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":{"0":"post-17094","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized-th","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/posts\/17094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/comments?post=17094"}],"version-history":[{"count":2,"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/posts\/17094\/revisions"}],"predecessor-version":[{"id":17102,"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/posts\/17094\/revisions\/17102"}],"wp:attachment":[{"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/media?parent=17094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/categories?post=17094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forest.go.th\/phitsanulok\/wp-json\/wp\/v2\/tags?post=17094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}