{"id":14352,"date":"2024-10-02T14:07:35","date_gmt":"2024-10-02T07:07:35","guid":{"rendered":"https:\/\/www.forest.go.th\/orip\/?p=14352"},"modified":"2024-10-02T14:07:40","modified_gmt":"2024-10-02T07:07:40","slug":"%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/","title":{"rendered":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&#8221; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14352\" class=\"elementor elementor-14352\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1c719c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1c719c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ee7ddd\" data-id=\"2ee7ddd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7191f2 elementor-widget elementor-widget-image\" data-id=\"d7191f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1-1024x683.jpg\" class=\"attachment-large size-large wp-image-14353 no-lazy\" alt=\"\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea403c3 elementor-widget elementor-widget-text-editor\" data-id=\"ea403c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #000000; font-family: Sarabun;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&#8221; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2567 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2d\u0e35\u0e42\u0e04 \u0e42\u0e04\u0e0b\u0e35 \u0e1a\u0e23\u0e35\u0e0a\u0e1f\u0e23\u0e2d\u0e19\u0e15\u0e4c \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26-28 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7dab3b elementor-widget elementor-widget-image-gallery\" data-id=\"f7dab3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='czr-gallery row flex-row czr-gallery-style gallery galleryid-14352 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3.jpg class=\"bg-link\"><\/a><img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_3.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5.jpg class=\"bg-link\"><\/a><img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_5.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_2.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_6.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_4.jpg 2048w\" \/>\r\n                        <\/div><\/figure>\r\n                  <\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142691b elementor-widget elementor-widget-text-editor\" data-id=\"142691b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong><span style=\"color: #000000; font-family: Sarabun;\">\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e2b\u0e25\u0e21\u0e1c\u0e31\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e2d\u0e31\u0e19\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e2b\u0e25\u0e21 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b46c110 elementor-widget elementor-widget-image-gallery\" data-id=\"b46c110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='czr-gallery row flex-row czr-gallery-style gallery galleryid-14352 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_36.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_37.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_34.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_1.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_28.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_26.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_27.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_29.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_30.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_31.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_32.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_33.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_35.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_4.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_23.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_22.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_21.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_24.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_39.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_41.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_38.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_12.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_11.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_3.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_5.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_6.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_7.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_2.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_8.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_13.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_15.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_9.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_25.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_10.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_16.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_17.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_18.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_19.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e41\u0e2b\u0e25\u0e21\u0e1c_241002_20.jpg 2048w\" \/>\r\n                        <\/div><\/figure>\r\n                  <\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6132e elementor-widget elementor-widget-text-editor\" data-id=\"7c6132e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong><span style=\"color: #000000; font-family: Sarabun;\">\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91d7a0e elementor-widget elementor-widget-image-gallery\" data-id=\"91d7a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='czr-gallery row flex-row czr-gallery-style gallery galleryid-14352 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_29.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_7.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_8.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_9.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_11.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_12.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_13.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_14.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_15.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_16.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_2.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_3.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_4.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_5.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_6.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_10.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_17.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_18.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_19.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_20.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_21.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_22.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_23.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_1.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_24.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_25.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_26.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_27.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48_241002_28.jpg 2048w\" \/>\r\n                        <\/div><\/figure>\r\n                  <\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0013f62 elementor-widget elementor-widget-text-editor\" data-id=\"0013f62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong><span style=\"color: #000000; font-family: Sarabun;\">\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e1a\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2b\u0e0d\u0e49\u0e32\u0e41\u0e1d\u0e01 ,\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e20\u0e32\u0e1e\u0e1b\u0e48\u0e32\u0e1a\u0e19\u0e20\u0e39\u0e40\u0e02\u0e32 ,\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19 ,\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e23\u0e2d\u0e1a\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e2d\u0e1a\u0e17\u0e35\u0e48 6 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92fa467 elementor-widget elementor-widget-image-gallery\" data-id=\"92fa467\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='czr-gallery row flex-row czr-gallery-style gallery galleryid-14352 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_20.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_21.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_35.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_27.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_22.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_23.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_1.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_3.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_11.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_2.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_4.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_5.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_6.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_7.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_8.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_9.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_10.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_12.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_13.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_14.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_15.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_16.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_17.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_18.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_19.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_24.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_25.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_26.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_28.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_29.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_30.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_31.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_32.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_33.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_34.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_36.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_37.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_38.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_39.jpg 2048w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40-768x512.jpg\" class=\"attachment-medium_large size-medium_large no-lazy\" alt=\"\" sizes=\"(min-width: 1200px) 350px, (min-width: 992px) 290px, (min-width: 768px) 210px, (min-width: 576px) 150px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40-768x512.jpg 768w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40-300x200.jpg 300w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40-1024x683.jpg 1024w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40-1536x1024.jpg 1536w, https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19_241002_40.jpg 2048w\" \/>\r\n                        <\/div><\/figure>\r\n                  <\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":257,"featured_media":14353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":{"0":"post-14352","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &quot;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&quot; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forest.go.th\/orip\/\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e07\u0e1b\u0e0f\u0e1a\u0e15\u0e01\u0e32\u0e23\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &quot;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&quot; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forest.go.th\/orip\/\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e07\u0e1b\u0e0f\u0e1a\u0e15\u0e01\u0e32\u0e23\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T07:07:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T07:07:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\"},\"author\":{\"name\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/#\\\/schema\\\/person\\\/a9f1d89428d6a0b28b612d8dca709c55\"},\"headline\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&#8221; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567\",\"datePublished\":\"2024-10-02T07:07:35+00:00\",\"dateModified\":\"2024-10-02T07:07:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/#\\\/schema\\\/person\\\/a9f1d89428d6a0b28b612d8dca709c55\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2024\\\/10\\\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\",\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \\\"\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\\\" \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2024\\\/10\\\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg\",\"datePublished\":\"2024-10-02T07:07:35+00:00\",\"dateModified\":\"2024-10-02T07:07:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2024\\\/10\\\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2024\\\/10\\\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&#8221; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/#website\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/#\\\/schema\\\/person\\\/a9f1d89428d6a0b28b612d8dca709c55\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/#\\\/schema\\\/person\\\/a9f1d89428d6a0b28b612d8dca709c55\",\"name\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2022\\\/06\\\/111.png\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2022\\\/06\\\/111.png\",\"contentUrl\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2022\\\/06\\\/111.png\",\"width\":260,\"height\":260,\"caption\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2022\\\/06\\\/111.png\"},\"sameAs\":[\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/\"],\"url\":\"https:\\\/\\\/www.forest.go.th\\\/orip\\\/author\\\/rfd025792740\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \"\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\" \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forest.go.th\/orip\/\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e07\u0e1b\u0e0f\u0e1a\u0e15\u0e01\u0e32\u0e23\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \"\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\" \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29","og_url":"https:\/\/www.forest.go.th\/orip\/\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e07\u0e1b\u0e0f\u0e1a\u0e15\u0e01\u0e32\u0e23\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29","article_published_time":"2024-10-02T07:07:35+00:00","article_modified_time":"2024-10-02T07:07:40+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg","type":"image\/jpeg"}],"author":"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#article","isPartOf":{"@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/"},"author":{"name":"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23","@id":"https:\/\/www.forest.go.th\/orip\/#\/schema\/person\/a9f1d89428d6a0b28b612d8dca709c55"},"headline":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&#8221; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567","datePublished":"2024-10-02T07:07:35+00:00","dateModified":"2024-10-02T07:07:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/www.forest.go.th\/orip\/#\/schema\/person\/a9f1d89428d6a0b28b612d8dca709c55"},"image":{"@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/","url":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/","name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \"\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\" \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29","isPartOf":{"@id":"https:\/\/www.forest.go.th\/orip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#primaryimage"},"image":{"@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg","datePublished":"2024-10-02T07:07:35+00:00","dateModified":"2024-10-02T07:07:40+00:00","breadcrumb":{"@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#primaryimage","url":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg","contentUrl":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2024\/10\/LINE_ALBUM_\u0e23\u0e39\u0e1b\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14_241002_1.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.forest.go.th\/orip\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%9a%e0%b8%95%e0%b8%81%e0%b8%b2%e0%b8%a3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.forest.go.th\/orip\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29&#8221; \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567"}]},{"@type":"WebSite","@id":"https:\/\/www.forest.go.th\/orip\/#website","url":"https:\/\/www.forest.go.th\/orip\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29","description":"","publisher":{"@id":"https:\/\/www.forest.go.th\/orip\/#\/schema\/person\/a9f1d89428d6a0b28b612d8dca709c55"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forest.go.th\/orip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":["Person","Organization"],"@id":"https:\/\/www.forest.go.th\/orip\/#\/schema\/person\/a9f1d89428d6a0b28b612d8dca709c55","name":"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2022\/06\/111.png","url":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2022\/06\/111.png","contentUrl":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2022\/06\/111.png","width":260,"height":260,"caption":"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e04\u0e23"},"logo":{"@id":"https:\/\/www.forest.go.th\/orip\/wp-content\/uploads\/sites\/100\/2022\/06\/111.png"},"sameAs":["https:\/\/www.forest.go.th\/orip\/"],"url":"https:\/\/www.forest.go.th\/orip\/author\/rfd025792740\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/posts\/14352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/users\/257"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/comments?post=14352"}],"version-history":[{"count":5,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/posts\/14352\/revisions"}],"predecessor-version":[{"id":14473,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/posts\/14352\/revisions\/14473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/media\/14353"}],"wp:attachment":[{"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/media?parent=14352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/categories?post=14352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forest.go.th\/orip\/wp-json\/wp\/v2\/tags?post=14352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}