{"id":7837,"date":"2025-09-23T11:34:13","date_gmt":"2025-09-23T04:34:13","guid":{"rendered":"https:\/\/www.forest.go.th\/it\/?p=7837"},"modified":"2025-09-23T11:34:15","modified_gmt":"2025-09-23T04:34:15","slug":"%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2","status":"publish","type":"post","link":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/","title":{"rendered":"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/09\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B2%E0%B8%A8%E0%B8%9C%E0%B8%B9%E0%B9%89%E0%B8%8A%E0%B8%99%E0%B8%B0%E0%B8%8B%E0%B8%B7%E0%B9%89%E0%B8%AD%E0%B8%AD%E0%B8%B8%E0%B8%9B%E0%B8%81%E0%B8%A3%E0%B8%93%E0%B9%8C%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B8%AD%E0%B8%82%E0%B9%88%E0%B8%B2%E0%B8%A2%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/09\/WIN_09092567.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e2e\u0e10 9343 \u0e01\u0e17\u0e21 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/wp-content\/uploads\/2024\/08\/WINNER_20240827.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e36\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e33\u0e19\u0e27\u0e19 5 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/wp-content\/uploads\/2024\/08\/WINNER_202408271.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/08\/winner_20240815.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/08\/winner_20240806.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u00a0\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/07\/WIN16072024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e1b\u0e35 2566 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/07\/fitc0005_rotated.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 2 \u0e01\u0e22 9703 \u0e01\u0e17\u0e21. \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/06\/win_20240620.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/06\/20240712_winner.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2567 (\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2) \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/A1-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2567 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/Increase-efficiency-project-phase-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e23\u0e30\u0e22\u0e301 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B2%E0%B8%A8%E0%B8%A2%E0%B8%81%E0%B9%80%E0%B8%A5%E0%B8%B4%E0%B8%81-com.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2567 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/%E0%B8%94%E0%B9%89%E0%B8%B2%E0%B8%99%E0%B9%80%E0%B8%97%E0%B8%84%E0%B9%82%E0%B8%99%E0%B9%82%E0%B8%A5%E0%B8%A2%E0%B8%B5%E0%B8%AA%E0%B8%B2%E0%B8%A3%E0%B8%AA%E0%B8%99%E0%B9%80%E0%B8%97%E0%B8%A8.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/%E0%B8%94%E0%B9%89%E0%B8%B2%E0%B8%99%E0%B8%98%E0%B8%B8%E0%B8%A3%E0%B8%81%E0%B8%B2%E0%B8%A3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/%E0%B8%94%E0%B9%89%E0%B8%B2%E0%B8%99%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%84%E0%B8%AD%E0%B8%A1%E0%B8%9E%E0%B8%B4%E0%B8%A7%E0%B9%80%E0%B8%95%E0%B8%AD%E0%B8%A3%E0%B9%8C.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/air-conditioner.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e25\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e08\u0e33\u0e19\u0e27\u0e19 5 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/buy-printer-ink.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e36\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B2%E0%B8%A8-A4.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e16\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19 100 \u0e23\u0e35\u0e21 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/Draft-project-for-developing-the-equipment-registration-management-system1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c(e-bidding)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/05\/Draft-project-to-increase-service-efficiency-Phase-11.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e23\u0e30\u0e22\u0e30 \u0e51 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c(e-bidding<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/04\/Draft-project-for-developing-the-equipment-registration-management-system.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e48\u0e32\u0e07 TOR \u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e01\u0e25\u0e32\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/04\/Draft-project-to-increase-service-efficiency-Phase-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e48\u0e32\u0e07 TOR \u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e01\u0e25\u0e32\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e23\u0e30\u0e22\u0e30 \u0e51 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/04\/%E0%B9%82%E0%B8%84%E0%B8%A3%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%88%E0%B8%B1%E0%B8%94%E0%B8%AB%E0%B8%B2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%84%E0%B8%AD%E0%B8%A1%E0%B8%9E%E0%B8%B4%E0%B8%A7%E0%B9%80%E0%B8%95%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%AD%E0%B8%B8%E0%B8%9B%E0%B8%81%E0%B8%A3%E0%B8%931.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/03\/O-14.xlsx\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e07\u0e1a\u0e23\u0e32\u0e22\u0e08\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e14\u0e07\u0e1a\u0e25\u0e07\u0e17\u0e38\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1b\u0e35 \u0e1e.\u0e28. 2567<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/01\/%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%88%E0%B8%B3%E0%B8%AB%E0%B8%99%E0%B9%88%E0%B8%B2%E0%B8%A2%E0%B8%9E%E0%B8%B1%E0%B8%AA%E0%B8%94%E0%B8%B8.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e0a\u0e33\u0e23\u0e38\u0e14\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e20\u0e32\u0e1e \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2566 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14 \u0e08\u0e33\u0e19\u0e27\u0e19 30 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/02\/Repair-internet-network-cables.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e2a\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e1b\u0e48\u0e32 (\u0e28\u0e1b\u0e01.\u0e1e\u0e1b.) \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2024\/02\/Rent-a-server-backup-device.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":466,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-7837","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized","7":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 - \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forest.go.th\/it\/blog\/\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07-\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30-2\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 - \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forest.go.th\/it\/blog\/\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07-\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T04:34:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T04:34:15+00:00\" \/>\n<meta name=\"author\" content=\"kanokphan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kanokphan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/\"},\"author\":{\"name\":\"kanokphan\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#\\\/schema\\\/person\\\/e5c376d241ca69ebab1bd15ba76260d2\"},\"headline\":\"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567\",\"datePublished\":\"2025-09-23T04:34:13+00:00\",\"dateModified\":\"2025-09-23T04:34:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#organization\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/\",\"name\":\"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 - \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#website\"},\"datePublished\":\"2025-09-23T04:34:13+00:00\",\"dateModified\":\"2025-09-23T04:34:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/\",\"name\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\",\"description\":\"\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#organization\",\"name\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2023\\\/02\\\/new-rfd-web-logo-it.png\",\"contentUrl\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2023\\\/02\\\/new-rfd-web-logo-it.png\",\"width\":720,\"height\":200,\"caption\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/#\\\/schema\\\/person\\\/e5c376d241ca69ebab1bd15ba76260d2\",\"name\":\"kanokphan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ebbb1f00d127de920566848b13cba6a7925b039129f2fd3ccfbad17f132090c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ebbb1f00d127de920566848b13cba6a7925b039129f2fd3ccfbad17f132090c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ebbb1f00d127de920566848b13cba6a7925b039129f2fd3ccfbad17f132090c?s=96&d=mm&r=g\",\"caption\":\"kanokphan\"},\"url\":\"https:\\\/\\\/www.forest.go.th\\\/it\\\/blog\\\/author\\\/kanokphan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 - \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forest.go.th\/it\/blog\/\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07-\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30-2\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 - \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49","og_url":"https:\/\/www.forest.go.th\/it\/blog\/\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07-\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30-2\/","og_site_name":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49","article_published_time":"2025-09-23T04:34:13+00:00","article_modified_time":"2025-09-23T04:34:15+00:00","author":"kanokphan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kanokphan","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/#article","isPartOf":{"@id":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/"},"author":{"name":"kanokphan","@id":"https:\/\/www.forest.go.th\/it\/#\/schema\/person\/e5c376d241ca69ebab1bd15ba76260d2"},"headline":"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567","datePublished":"2025-09-23T04:34:13+00:00","dateModified":"2025-09-23T04:34:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/www.forest.go.th\/it\/#organization"},"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/","url":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/","name":"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 - \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49","isPartOf":{"@id":"https:\/\/www.forest.go.th\/it\/#website"},"datePublished":"2025-09-23T04:34:13+00:00","dateModified":"2025-09-23T04:34:15+00:00","breadcrumb":{"@id":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.forest.go.th\/it\/blog\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%8b%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%87-%e0%b8%9b%e0%b8%b5%e0%b8%87%e0%b8%9a%e0%b8%9b%e0%b8%a3%e0%b8%b0-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.forest.go.th\/it\/"},{"@type":"ListItem","position":2,"name":"\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567"}]},{"@type":"WebSite","@id":"https:\/\/www.forest.go.th\/it\/#website","url":"https:\/\/www.forest.go.th\/it\/","name":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49","description":"\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28","publisher":{"@id":"https:\/\/www.forest.go.th\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forest.go.th\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.forest.go.th\/it\/#organization","name":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49","url":"https:\/\/www.forest.go.th\/it\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.forest.go.th\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2023\/02\/new-rfd-web-logo-it.png","contentUrl":"https:\/\/www.forest.go.th\/it\/wp-content\/uploads\/sites\/21\/2023\/02\/new-rfd-web-logo-it.png","width":720,"height":200,"caption":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49"},"image":{"@id":"https:\/\/www.forest.go.th\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.forest.go.th\/it\/#\/schema\/person\/e5c376d241ca69ebab1bd15ba76260d2","name":"kanokphan","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/9ebbb1f00d127de920566848b13cba6a7925b039129f2fd3ccfbad17f132090c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ebbb1f00d127de920566848b13cba6a7925b039129f2fd3ccfbad17f132090c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebbb1f00d127de920566848b13cba6a7925b039129f2fd3ccfbad17f132090c?s=96&d=mm&r=g","caption":"kanokphan"},"url":"https:\/\/www.forest.go.th\/it\/blog\/author\/kanokphan\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/posts\/7837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/users\/466"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/comments?post=7837"}],"version-history":[{"count":1,"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/posts\/7837\/revisions"}],"predecessor-version":[{"id":7838,"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/posts\/7837\/revisions\/7838"}],"wp:attachment":[{"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/media?parent=7837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/categories?post=7837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forest.go.th\/it\/wp-json\/wp\/v2\/tags?post=7837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}