{"id":404891,"date":"2020-07-27T11:04:08","date_gmt":"2020-07-27T04:04:08","guid":{"rendered":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg"},"modified":"2021-04-29T11:47:44","modified_gmt":"2021-04-29T04:47:44","slug":"one-page-63_%e0%b9%92%e0%b9%90%e0%b9%90%e0%b9%97%e0%b9%92%e0%b9%97_0","status":"inherit","type":"attachment","link":"https:\/\/www.forest.go.th\/community\/ce010\/one-page-63_%e0%b9%92%e0%b9%90%e0%b9%90%e0%b9%97%e0%b9%92%e0%b9%97_0\/","title":{"rendered":"One page 63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0"},"author":244,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-404891","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-212x300.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-212x300.jpg 212w, https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-724x1024.jpg 724w, https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-768x1086.jpg 768w, https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg 905w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>\u0e1b\u0e25\u0e39\u0e01\u0e1b\u0e48\u0e32<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":905,"height":1280,"file":"2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg","sizes":{"medium":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-212x300.jpg"},"large":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-724x1024.jpg","width":724,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-724x1024.jpg"},"thumbnail":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-150x150.jpg"},"medium_large":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-768x1086.jpg","width":768,"height":1086,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-768x1086.jpg"},"tc_rectangular_size":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x500.jpg","width":905,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x500.jpg"},"tc-grid-full":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x350.jpg","width":905,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x350.jpg"},"tc-grid":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-570x350.jpg","width":570,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-570x350.jpg"},"tc-thumb":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-270x250.jpg"},"slider-full":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x500.jpg","width":905,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x500.jpg"},"slider":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x500.jpg","width":905,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-905x500.jpg"},"sow-carousel-default":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0-272x182.jpg"},"full":{"file":"One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg","width":905,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":402768,"source_url":"https:\/\/www.forest.go.th\/community\/wp-content\/uploads\/sites\/16\/2020\/07\/One-page-63_\u0e52\u0e50\u0e50\u0e57\u0e52\u0e57_0.jpg","_links":{"self":[{"href":"https:\/\/www.forest.go.th\/community\/wp-json\/wp\/v2\/media\/404891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest.go.th\/community\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.forest.go.th\/community\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/community\/wp-json\/wp\/v2\/users\/244"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/community\/wp-json\/wp\/v2\/comments?post=404891"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":402768,"href":"https:\/\/www.forest.go.th\/community\/wp-json\/wp\/v2\/pages\/402768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}