{"id":11551,"date":"2022-09-01T15:39:09","date_gmt":"2022-09-01T08:39:09","guid":{"rendered":"https:\/\/www.forest.go.th\/chiangmai1\/?p=11551"},"modified":"2022-09-01T15:39:14","modified_gmt":"2022-09-01T08:39:14","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b9%88%e0%b8%b2%e0%b9%84%e0%b8%a1%e0%b9%89-%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87-574","status":"publish","type":"post","link":"https:\/\/www.forest.go.th\/chiangmai1\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b9%88%e0%b8%b2%e0%b9%84%e0%b8%a1%e0%b9%89-%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87-574\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"1024\" src=\"https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158-727x1024.jpg\" alt=\"\" class=\"wp-image-11554\" srcset=\"https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158-727x1024.jpg 727w, https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158-213x300.jpg 213w, https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158-768x1081.jpg 768w, https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158-1091x1536.jpg 1091w, https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158-1454x2048.jpg 1454w, https:\/\/www.forest.go.th\/chiangmai1\/wp-content\/uploads\/sites\/38\/2022\/09\/5158.jpg 1725w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":217,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[79],"tags":[],"class_list":{"0":"post-11551","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category--th","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/posts\/11551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/users\/217"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/comments?post=11551"}],"version-history":[{"count":1,"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/posts\/11551\/revisions"}],"predecessor-version":[{"id":11556,"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/posts\/11551\/revisions\/11556"}],"wp:attachment":[{"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/media?parent=11551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/categories?post=11551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forest.go.th\/chiangmai1\/wp-json\/wp\/v2\/tags?post=11551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}